{"id":275,"date":"2025-01-03T19:28:20","date_gmt":"2025-01-03T19:28:20","guid":{"rendered":"https:\/\/ngo.carmelites.net\/?p=275"},"modified":"2025-01-03T19:35:13","modified_gmt":"2025-01-03T19:35:13","slug":"ecological-conversion","status":"publish","type":"post","link":"https:\/\/carmelitengo.org\/it\/projects\/ecological-conversion\/","title":{"rendered":"Conversione ecologica"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"275\" class=\"elementor elementor-275\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-230dc53a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"230dc53a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-319fbf1d\" data-id=\"319fbf1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84a522a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"84a522a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"520\" height=\"416\" src=\"https:\/\/carmelitengo.org\/wp-content\/uploads\/2025\/01\/Ecological-Converison-5x4-1.webp\" class=\"attachment-large size-large wp-image-277\" alt=\"\" srcset=\"https:\/\/carmelitengo.org\/wp-content\/uploads\/2025\/01\/Ecological-Converison-5x4-1.webp 520w, https:\/\/carmelitengo.org\/wp-content\/uploads\/2025\/01\/Ecological-Converison-5x4-1-300x240.webp 300w\" sizes=\"(max-width: 520px) 100vw, 520px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4fdc4ae\" data-id=\"4fdc4ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6707982 elementor-widget elementor-widget-text-editor\" data-id=\"6707982\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"tit-single\">Libro: Conversione ecologica. Nella speranza di \"un cielo nuovo e una terra nuova\" (Ap 21,1)<\/h1>\r\n<div class=\"contenido-single\">\r\n\r\n\"Conversione ecologica\" \u00e8 una piccola opera con 37 brevi riflessioni scritte in chiave ecologica da P. Eduardo Agosta Scarel, O.Carm. e pubblicata dalla ONG carmelitana. Offre ai cristiani cattolici e ai credenti alcune considerazioni di fede per incoraggiarci a intraprendere una cura attiva per l'ambiente, la terra, la nostra casa comune.\r\n\r\nLa cura attiva dell'ambiente \u00e8 solo l'inizio di un processo profondo e urgente di \"conversione ecologica\", che inizia con la Pasqua di Cristo, si prolunga nel tempo con la forza dello Spirito e culminer\u00e0 quando arriveranno \"i cieli nuovi e la terra nuova\" (Ap 21,1).\r\n\r\nLe riflessioni partono dal contributo della scienza, da alcuni testi chiave della Bibbia e dalla teologia \"ecologica\" presente negli insegnamenti degli ultimi Papi della Chiesa, da Paolo VI a Francesco.\r\n<div class=\"contenido-single\">\r\n<div class=\"texto_noti_home\">\r\n\r\nDisponibile gratuitamente al sito\u00a0<a href=\"https:\/\/books.apple.com\/us\/book\/ecological-conversion-in-hope-of-new-heaven-and-new-earth\/id1465224557\" target=\"_blank\" rel=\"noopener noreferrer\">Apple Store.<\/a>\r\n\r\nAnche in formato PDF stampabile da\u00a0<a href=\"https:\/\/www.carmelitas.es\/wp-content\/uploads\/2019\/05\/Ecological-Conversion-Carmelite-NGO-UN.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">questo sito<\/a>\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Book: Ecological Conversion. In hope of \u201ca new heaven and a new earth \u201c (Rev 21:1) \u201cEcological conversion\u201d is a small work with 37 brief reflections written in ecological key by Fr. Eduardo Agosta Scarel, O.Carm., and published by the Carmelite NGO. It offers Catholic Christians and believers some considerations of faith to encourage us [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":277,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projects"],"_links":{"self":[{"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/posts\/275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/comments?post=275"}],"version-history":[{"count":7,"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/posts\/275\/revisions"}],"predecessor-version":[{"id":290,"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/posts\/275\/revisions\/290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/media\/277"}],"wp:attachment":[{"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/media?parent=275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/categories?post=275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carmelitengo.org\/it\/wp-json\/wp\/v2\/tags?post=275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}